{"id":997,"date":"2021-04-16T19:22:28","date_gmt":"2021-04-16T17:22:28","guid":{"rendered":"http:\/\/blaum.orange-cube.de\/?post_type=anwlte&#038;p=997"},"modified":"2026-04-23T09:56:18","modified_gmt":"2026-04-23T07:56:18","slug":"dr-lars-konukiewitz","status":"publish","type":"anwlte","link":"https:\/\/blaum.de\/en\/Anw\u00e4lte\/dr-lars-konukiewitz\/","title":{"rendered":"Dr. Lars Konukiewitz"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"997\" class=\"elementor elementor-997\" data-elementor-post-type=\"anwlte\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23bfa189 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23bfa189\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64c5aa70\" data-id=\"64c5aa70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ed242b elementor-widget elementor-widget-text-editor\" data-id=\"31ed242b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p><strong>Practice Areas:<\/strong><br>Corporate law, mergers and acquisitions (M&amp;A), shareholder disputes and commercial law&nbsp;&nbsp;<\/p>\n<p><strong>Curriculum:<\/strong><br>Studied law at the University of Heidelberg; exchange assistant at the Institute for Foreign and International Private and Commercial Law of the University of Heidelberg at the Faculty of Law of the University of Montpellier I; previously spent extended periods abroad in the USA and France; occupation in a supra-regional commercial law firm<\/p>\n<p><\/p>\n<p>Doctorate in 2012<br>Admitted to the bar in Bremen in 2012<br>Certified specialist lawyer in commercial and corporate law since 2015<\/p><p><span style=\"word-spacing: 1.6px;\">Bestellung zum Notar mit Amtssitz in Bremen: 2026<\/span>&nbsp;<\/p>\n<p>Languages: French, English<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Lawyer and notary (Bremen office), certified specialist lawyer in commercial and corporate law<\/p>","protected":false},"author":1,"featured_media":998,"menu_order":19,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[15,20,10,9,37],"anwalt_kategorien":[],"class_list":["post-997","anwlte","type-anwlte","status-publish","format-standard","has-post-thumbnail","hentry","category-bankrecht-factoring","category-bremen","category-gesellschaftsrecht","category-handelsrecht","category-notare"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Lars Konukiewitz - blaum<\/title>\n<meta name=\"description\" content=\"Rechtsanwalt,Fachanwalt f\u00fcr Handels- und Gesellschaftsrecht\u00a0T\u00e4tigkeitsschwerpunkte:Gesellschaftsrecht, Unternehmensk\u00e4ufe (M&amp;A), Handelsrecht, Bankrecht\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blaum.de\/en\/Anw\u00e4lte\/dr-lars-konukiewitz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Lars Konukiewitz - blaum\" \/>\n<meta property=\"og:description\" content=\"Rechtsanwalt,Fachanwalt f\u00fcr Handels- und Gesellschaftsrecht\u00a0T\u00e4tigkeitsschwerpunkte:Gesellschaftsrecht, Unternehmensk\u00e4ufe (M&amp;A), Handelsrecht, Bankrecht\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blaum.de\/en\/Anw\u00e4lte\/dr-lars-konukiewitz\/\" \/>\n<meta property=\"og:site_name\" content=\"blaum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T07:56:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/resources_Server_P-neu_Lars_Konukiewitz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/\",\"url\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/\",\"name\":\"Dr. Lars Konukiewitz - blaum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blaum.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blaum.de\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/resources_Server_P-neu_Lars_Konukiewitz.jpg\",\"datePublished\":\"2021-04-16T17:22:28+00:00\",\"dateModified\":\"2026-04-23T07:56:18+00:00\",\"description\":\"Rechtsanwalt,Fachanwalt f\u00fcr Handels- und Gesellschaftsrecht\u00a0T\u00e4tigkeitsschwerpunkte:Gesellschaftsrecht, Unternehmensk\u00e4ufe (M&A), Handelsrecht, Bankrecht\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blaum.de\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/resources_Server_P-neu_Lars_Konukiewitz.jpg\",\"contentUrl\":\"https:\\\/\\\/blaum.de\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/resources_Server_P-neu_Lars_Konukiewitz.jpg\",\"width\":920,\"height\":522,\"caption\":\"Dr. Lars Konukiewitz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/dr-lars-konukiewitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blaum.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anw\u00e4lte\",\"item\":\"https:\\\/\\\/blaum.de\\\/Anw\u00e4lte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr. Lars Konukiewitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blaum.de\\\/#website\",\"url\":\"https:\\\/\\\/blaum.de\\\/\",\"name\":\"blaum\",\"description\":\"Blaum Dettmers Rabstein Rechtsanwaltspartnerschaft mbB\",\"publisher\":{\"@id\":\"https:\\\/\\\/blaum.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blaum.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blaum.de\\\/#organization\",\"name\":\"Blaum Dettmers Rabstein\",\"url\":\"https:\\\/\\\/blaum.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blaum.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blaum.de\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-blaum-dettmers-rabstein.png\",\"contentUrl\":\"https:\\\/\\\/blaum.de\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-blaum-dettmers-rabstein.png\",\"width\":721,\"height\":236,\"caption\":\"Blaum Dettmers Rabstein\"},\"image\":{\"@id\":\"https:\\\/\\\/blaum.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.xing.com\\\/pages\\\/blaumdettmersrabstein\",\"https:\\\/\\\/www.instagram.com\\\/blaumdettmersrabstein\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/uas\\\/login?session_redirect=httpswww.linkedin.comcompany6786448adminfeedposts\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Lars Konukiewitz - blaum","description":"Rechtsanwalt,Fachanwalt f\u00fcr Handels- und Gesellschaftsrecht\u00a0T\u00e4tigkeitsschwerpunkte:Gesellschaftsrecht, Unternehmensk\u00e4ufe (M&A), Handelsrecht, Bankrecht\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blaum.de\/en\/Anw\u00e4lte\/dr-lars-konukiewitz\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Lars Konukiewitz - blaum","og_description":"Rechtsanwalt,Fachanwalt f\u00fcr Handels- und Gesellschaftsrecht\u00a0T\u00e4tigkeitsschwerpunkte:Gesellschaftsrecht, Unternehmensk\u00e4ufe (M&A), Handelsrecht, Bankrecht\u00a0","og_url":"https:\/\/blaum.de\/en\/Anw\u00e4lte\/dr-lars-konukiewitz\/","og_site_name":"blaum","article_modified_time":"2026-04-23T07:56:18+00:00","og_image":[{"width":920,"height":522,"url":"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/resources_Server_P-neu_Lars_Konukiewitz.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/","url":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/","name":"Dr. Lars Konukiewitz - blaum","isPartOf":{"@id":"https:\/\/blaum.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/#primaryimage"},"image":{"@id":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/#primaryimage"},"thumbnailUrl":"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/resources_Server_P-neu_Lars_Konukiewitz.jpg","datePublished":"2021-04-16T17:22:28+00:00","dateModified":"2026-04-23T07:56:18+00:00","description":"Rechtsanwalt,Fachanwalt f\u00fcr Handels- und Gesellschaftsrecht\u00a0T\u00e4tigkeitsschwerpunkte:Gesellschaftsrecht, Unternehmensk\u00e4ufe (M&A), Handelsrecht, Bankrecht\u00a0","breadcrumb":{"@id":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/#primaryimage","url":"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/resources_Server_P-neu_Lars_Konukiewitz.jpg","contentUrl":"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/resources_Server_P-neu_Lars_Konukiewitz.jpg","width":920,"height":522,"caption":"Dr. Lars Konukiewitz"},{"@type":"BreadcrumbList","@id":"https:\/\/blaum.de\/Anw\u00e4lte\/dr-lars-konukiewitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blaum.de\/"},{"@type":"ListItem","position":2,"name":"Anw\u00e4lte","item":"https:\/\/blaum.de\/Anw\u00e4lte\/"},{"@type":"ListItem","position":3,"name":"Dr. Lars Konukiewitz"}]},{"@type":"WebSite","@id":"https:\/\/blaum.de\/#website","url":"https:\/\/blaum.de\/","name":"blaum","description":"Blaum Dettmers Rabstein Rechtsanwaltspartnerschaft mbB","publisher":{"@id":"https:\/\/blaum.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blaum.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blaum.de\/#organization","name":"Blaum Dettmers Rabstein","url":"https:\/\/blaum.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blaum.de\/#\/schema\/logo\/image\/","url":"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/logo-blaum-dettmers-rabstein.png","contentUrl":"https:\/\/blaum.de\/wp-content\/uploads\/2021\/04\/logo-blaum-dettmers-rabstein.png","width":721,"height":236,"caption":"Blaum Dettmers Rabstein"},"image":{"@id":"https:\/\/blaum.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.xing.com\/pages\/blaumdettmersrabstein","https:\/\/www.instagram.com\/blaumdettmersrabstein\/","https:\/\/www.linkedin.com\/uas\/login?session_redirect=httpswww.linkedin.comcompany6786448adminfeedposts"]}]}},"_links":{"self":[{"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/anwlte\/997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/anwlte"}],"about":[{"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/types\/anwlte"}],"author":[{"embeddable":true,"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/anwlte\/997\/revisions"}],"predecessor-version":[{"id":8125,"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/anwlte\/997\/revisions\/8125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/media\/998"}],"wp:attachment":[{"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/media?parent=997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/categories?post=997"},{"taxonomy":"anwalt_kategorien","embeddable":true,"href":"https:\/\/blaum.de\/en\/wp-json\/wp\/v2\/anwalt_kategorien?post=997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}